{"id":3318,"date":"2024-03-05T09:52:44","date_gmt":"2024-03-05T09:52:44","guid":{"rendered":"https:\/\/musing-lumiere.49-12-134-4.plesk.page\/?page_id=3318"},"modified":"2024-03-05T15:19:32","modified_gmt":"2024-03-05T15:19:32","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3318\" class=\"elementor elementor-3318\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-343b2709 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"343b2709\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-69a83637\" data-id=\"69a83637\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94c136c elementor-widget elementor-widget-spacer\" data-id=\"94c136c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8784e6 elementor-widget elementor-widget-text-editor\" data-id=\"a8784e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sehr geehrte Damen und Herren,<\/p><p>wir freuen uns \u00fcber Ihr Interesse an unserem Unternehmen! Wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen, stehen wir Ihnen gerne zur Verf\u00fcgung. Sie k\u00f6nnen uns telefonisch unter der Nummer 0 59 66 &#8211; 444 erreichen. Unsere freundlichen Mitarbeiterinnen und Mitarbeiter stehen Ihnen von Montag bis Freitag in der Zeit von 8 bis 17 Uhr zur Verf\u00fcgung, um Ihre Anliegen pers\u00f6nlich zu besprechen.<\/p><p>Falls Sie au\u00dferhalb unserer Gesch\u00e4ftszeiten Kontakt aufnehmen m\u00f6chten, haben Sie auch die M\u00f6glichkeit, uns eine kurze Nachricht zukommen zu lassen. Nutzen Sie dazu bitte das untenstehende Formular. Wir legen gro\u00dfen Wert darauf, Ihnen zeitnah zu antworten, daher werden wir uns schnellstm\u00f6glich mit Ihnen in Verbindung setzen.<\/p><p>Vielen Dank f\u00fcr Ihr Vertrauen und Ihre Kontaktaufnahme.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf7e88c elementor-widget elementor-widget-shortcode\" data-id=\"7bf7e88c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-3364\"><form id=\"wpforms-form-3364\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3364\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/3318\"><noscript class=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Bitte aktiviere JavaScript in deinem Browser, um dieses Formular fertigzustellen.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-3364-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3364-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-3364-field_0-error\" required><label for=\"wpforms-3364-field_0\" class=\"wpforms-field-sublabel after \">Vorname<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3364-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-3364-field_0-last-error\" required><label for=\"wpforms-3364-field_0-last\" class=\"wpforms-field-sublabel after \">Nachname<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-3364-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-3364-field_1\">E-Mail-Adresse <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3364-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-3364-field_1-error\" required><\/div><div id=\"wpforms-3364-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3364-field_2\">Kommentar oder Nachricht<\/label><textarea id=\"wpforms-3364-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-3364-field_2-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-turnstile\" ><div class=\"g-recaptcha\" data-sitekey=\"0x4AAAAAAAic3E1eH4d8HO8J\" data-action=\"FormID-3364\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-turnstile=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3364\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><input type=\"hidden\" class=\"wpforms-token\" name=\"wpforms[token]\" value=\"69c7c3f53d5b9c164d97b7b989795ad7\" \/><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3364\" class=\"wpforms-submit\" data-alt-text=\"Wird gesendet\u00a0\u2026\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img decoding=\"async\" src=\"https:\/\/hochdruckreiniger-emsland.de\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Wird geladen\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sehr geehrte Damen und Herren, wir freuen uns \u00fcber Ihr Interesse an unserem Unternehmen! Wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen, stehen wir Ihnen gerne zur Verf\u00fcgung. Sie k\u00f6nnen uns telefonisch unter der Nummer 0 59 66 &#8211; 444 erreichen. Unsere freundlichen Mitarbeiterinnen und Mitarbeiter stehen Ihnen von Montag bis Freitag in der Zeit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3318","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/pages\/3318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/comments?post=3318"}],"version-history":[{"count":5,"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/pages\/3318\/revisions"}],"predecessor-version":[{"id":3369,"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/pages\/3318\/revisions\/3369"}],"wp:attachment":[{"href":"https:\/\/hochdruckreiniger-emsland.de\/index.php\/wp-json\/wp\/v2\/media?parent=3318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}